{"id":7920,"date":"2026-02-09T13:11:54","date_gmt":"2026-02-09T12:11:54","guid":{"rendered":"https:\/\/ecampania.it\/magazine\/?p=7920"},"modified":"2026-02-09T13:44:09","modified_gmt":"2026-02-09T12:44:09","slug":"napoli-la-biblioteca-nazionale-tra-libri-e-danza","status":"publish","type":"post","link":"https:\/\/ecampania.it\/magazine\/napoli-la-biblioteca-nazionale-tra-libri-e-danza\/","title":{"rendered":"Napoli. La Biblioteca Nazionale tra libri e danza"},"content":{"rendered":"\n<h4 class=\"wp-block-heading\"><strong>La grande Biblioteca di Napoli nelle sale del Palazzo Reale<\/strong><\/h4>\n\n\n\n<p>Libri e danza..connubio perfetto. Dove lo troviamo? Nella<strong> Biblioteca Nazionale di Napoli<\/strong> con sede, dal 1922, nel Palazzo Reale. Ma, attenzione, la sua origine \u00e8 molto pi\u00f9 antica. Risale al 1798, quando Re Ferdinando IV la trasfer\u00ed da Capodimonte al Palazzo degli Studi (oggi attuale Museo Archeologico Nazionale di Napoli).<\/p>\n\n\n\n<p>Da allora la biblioteca ha sede in un&#8217;ala del Palazzo Reale destinata, all&#8217;epoca, alle feste. Una lunga scalinata ed eleganti statue di danzatrici accompagnano il visitatore tra le sale della biblioteca ancora finemente affrescate. Prima di accedervi per\u00f2 ci sono due &#8220;custodi&#8221; d&#8217;eccezione. Due donne:<em> Eleonora Pimentel Fonseca<\/em>, la rivoluzionaria che qui fu anche bibliotecaria al servizio della regina <em>Maria Carolina<\/em>, e<em> Paolina Ranieri<\/em>. S\u00ec, anche lei qui perch\u00e9, con il fratello Antonio, ebbe il merito di ospitare amorevolmente a Napoli Giacomo Leopardi e custodirne le preziose opere. Ed indovinate un po&#8217; dove si trovano oggi? Proprio qui! Il Palazzo Reale di Napoli conserva l&#8217;80 per cento di tutto il corpus leopardiano e pochi sanno che qui ci sono addirittura Le operette morali, Lo zibaldone, L&#8217;infinito&#8230;<\/p>\n\n\n\n<p>Sconvolgente vero? Beh, poca roba se pensiamo che, in questa biblioteca, ci sono, appena appena, quattro milioni di opere, 10.000 testate periodiche, 13.000 carte geografiche, pi\u00f9 di 5000 incunaboli, manoscritti medioevali miniati, pi\u00f9 di millesettecento papiri di III a.C. provenienti da Ercolano. Numeri da primato, ed infatti \u00e8 la terza in Italia dopo Roma e Firenze! E diciamo pure che Leopardi qui \u00e8 anche in buona compagnia tra preziosissime opere e scritti di Tommaso d&#8217;Aquino, Ludovico Ariosto, Torquato Tasso, Salvatore Di Giacomo, Raffaele Viviani, Gabriele D&#8217;Annunzio etc&#8230;etc..<\/p>\n\n\n\n<p>Oltre all&#8217;immenso patrimonio librario accumulatosi nel corso dei secoli, anche&nbsp; in seguito a lasciti o soppressione di monasteri, non dimentichiamoci delle locations! Ci sono sale spettacolari:&nbsp;<\/p>\n\n\n\n<p>La<strong> sala Palatina<\/strong> con la biblioteca privata di <em>Ferdinando IV<\/em>, il tavolo ed il leggio rotante di Maria Carolina d&#8217;Austria con tanto di lettere e testamenti autografi dei sovrani. <strong>La sala da bagno <\/strong>con affreschi in stile pompeiano della <em>Regina Maria Teresa<\/em>. La <strong>cappella <\/strong>in stile neogotico che oggi ospita la biblioteca dell&#8217; amato attore <em>Nino Taranto<\/em>. La<strong> biblioteca di Elena<\/strong> <strong>d&#8217;Aosta<\/strong> con centinaia di volumi sull&#8217;anatomia umana (essendo lei una crocerossina) e una documentazione completa, tra fotografie, animali imbalsamati ed oggetti rari, dei suoi viaggi in Africa. Il Fondo Lucchesi del 1896 donato dal Conte Eduardo Lucchesi Palli con circa 2.500 volumi, documenti, lettere e spartiti sulla storia dello spettacolo, del teatro e della canzone napoletana.&nbsp;Qui si trovano documenti di <em>Verdi, Rossini, Paisiello <\/em>e numerosi schedari scritti a mano da<em> Salvatore Di Giacomo <\/em>che fu bibliotecario dei <em>Lucchesi Palli<\/em>. Emozionante poter vedere anche la sua bella scrivania. Carta, pelle,legno. Anche questo \u00e8 un connubio perfetto! Alcuni suoi testi sono scritti a mano finanche su un tamburello cos\u00ec come, in alcune vetrine, si trovano altre opere: preziose caricature realizzate dal tenore <em>Enrico Caruso<\/em> (abile caricaturista) e lettere autografe di Gioacchino Rossini con quel famoso congedo &#8220;Fatemi schiavo&#8221;. Fatemi schiavo, forma arcaica di saluto dal latino sclavus (servo vostro) e dal latino al veneto a S- Ciavo, il nostro Ciao.<\/p>\n\n\n\n<p>E allora, ciao ciao mia bellissima, inaspettata,sorprendente, biblioteca.<\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La grande Biblioteca di Napoli nelle sale del Palazzo Reale Libri e danza..connubio perfetto. Dove lo troviamo? Nella Biblioteca Nazionale di Napoli con sede, dal 1922, nel Palazzo Reale. Ma, attenzione, la sua origine \u00e8 molto pi\u00f9 antica. Risale al 1798, quando Re Ferdinando IV la trasfer\u00ed da Capodimonte al Palazzo degli Studi (oggi attuale [&hellip;]<\/p>\n","protected":false},"author":31,"featured_media":7921,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jnews-multi-image_gallery":[],"jnews_single_post":{"format":"standard"},"jnews_primary_category":[],"jnews_override_counter":[],"footnotes":""},"categories":[8],"tags":[32,151],"class_list":["post-7920","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura","tag-arte","tag-biblioteca"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Napoli. La Biblioteca Nazionale tra libri e danza - \u00e8campania<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ecampania.it\/magazine\/napoli-la-biblioteca-nazionale-tra-libri-e-danza\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Napoli. La Biblioteca Nazionale tra libri e danza - \u00e8campania\" \/>\n<meta property=\"og:description\" content=\"La grande Biblioteca di Napoli nelle sale del Palazzo Reale Libri e danza..connubio perfetto. Dove lo troviamo? Nella Biblioteca Nazionale di Napoli con sede, dal 1922, nel Palazzo Reale. Ma, attenzione, la sua origine \u00e8 molto pi\u00f9 antica. Risale al 1798, quando Re Ferdinando IV la trasfer\u00ed da Capodimonte al Palazzo degli Studi (oggi attuale [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ecampania.it\/magazine\/napoli-la-biblioteca-nazionale-tra-libri-e-danza\/\" \/>\n<meta property=\"og:site_name\" content=\"\u00e8campania\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ecampania.it\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-09T12:11:54+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-09T12:44:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ecampania.it\/magazine\/wp-content\/uploads\/2026\/02\/WhatsApp-Image-2026-02-09-at-12.12.54-3.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"2048\" \/>\n\t<meta property=\"og:image:height\" content=\"1536\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Valeria Buonomo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Valeria Buonomo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/ecampania.it\/magazine\/napoli-la-biblioteca-nazionale-tra-libri-e-danza\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/ecampania.it\/magazine\/napoli-la-biblioteca-nazionale-tra-libri-e-danza\/\"},\"author\":{\"name\":\"Valeria Buonomo\",\"@id\":\"https:\/\/ecampania.it\/magazine\/#\/schema\/person\/d5558105981d882b615d1982be1e3867\"},\"headline\":\"Napoli. La Biblioteca Nazionale tra libri e danza\",\"datePublished\":\"2026-02-09T12:11:54+00:00\",\"dateModified\":\"2026-02-09T12:44:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/ecampania.it\/magazine\/napoli-la-biblioteca-nazionale-tra-libri-e-danza\/\"},\"wordCount\":532,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/ecampania.it\/magazine\/#organization\"},\"image\":{\"@id\":\"https:\/\/ecampania.it\/magazine\/napoli-la-biblioteca-nazionale-tra-libri-e-danza\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/ecampania.it\/magazine\/wp-content\/uploads\/2026\/02\/WhatsApp-Image-2026-02-09-at-12.12.54-3.jpeg\",\"keywords\":[\"arte\",\"biblioteca\"],\"articleSection\":[\"Cultura\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/ecampania.it\/magazine\/napoli-la-biblioteca-nazionale-tra-libri-e-danza\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ecampania.it\/magazine\/napoli-la-biblioteca-nazionale-tra-libri-e-danza\/\",\"url\":\"https:\/\/ecampania.it\/magazine\/napoli-la-biblioteca-nazionale-tra-libri-e-danza\/\",\"name\":\"Napoli. La Biblioteca Nazionale tra libri e danza - \u00e8campania\",\"isPartOf\":{\"@id\":\"https:\/\/ecampania.it\/magazine\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/ecampania.it\/magazine\/napoli-la-biblioteca-nazionale-tra-libri-e-danza\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/ecampania.it\/magazine\/napoli-la-biblioteca-nazionale-tra-libri-e-danza\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/ecampania.it\/magazine\/wp-content\/uploads\/2026\/02\/WhatsApp-Image-2026-02-09-at-12.12.54-3.jpeg\",\"datePublished\":\"2026-02-09T12:11:54+00:00\",\"dateModified\":\"2026-02-09T12:44:09+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/ecampania.it\/magazine\/napoli-la-biblioteca-nazionale-tra-libri-e-danza\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ecampania.it\/magazine\/napoli-la-biblioteca-nazionale-tra-libri-e-danza\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/ecampania.it\/magazine\/napoli-la-biblioteca-nazionale-tra-libri-e-danza\/#primaryimage\",\"url\":\"https:\/\/ecampania.it\/magazine\/wp-content\/uploads\/2026\/02\/WhatsApp-Image-2026-02-09-at-12.12.54-3.jpeg\",\"contentUrl\":\"https:\/\/ecampania.it\/magazine\/wp-content\/uploads\/2026\/02\/WhatsApp-Image-2026-02-09-at-12.12.54-3.jpeg\",\"width\":2048,\"height\":1536},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ecampania.it\/magazine\/napoli-la-biblioteca-nazionale-tra-libri-e-danza\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/ecampania.it\/magazine\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Napoli. La Biblioteca Nazionale tra libri e danza\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ecampania.it\/magazine\/#website\",\"url\":\"https:\/\/ecampania.it\/magazine\/\",\"name\":\"Ecampania\",\"description\":\"Il primo portale dedicato al turismo ed alla cultura in Campania\",\"publisher\":{\"@id\":\"https:\/\/ecampania.it\/magazine\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ecampania.it\/magazine\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/ecampania.it\/magazine\/#organization\",\"name\":\"Ecampania\",\"url\":\"https:\/\/ecampania.it\/magazine\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/ecampania.it\/magazine\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/ecampania.it\/magazine\/wp-content\/uploads\/2025\/01\/fb.png\",\"contentUrl\":\"https:\/\/ecampania.it\/magazine\/wp-content\/uploads\/2025\/01\/fb.png\",\"width\":500,\"height\":500,\"caption\":\"Ecampania\"},\"image\":{\"@id\":\"https:\/\/ecampania.it\/magazine\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/ecampania.it\",\"https:\/\/www.instagram.com\/ecampania.it\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/ecampania.it\/magazine\/#\/schema\/person\/d5558105981d882b615d1982be1e3867\",\"name\":\"Valeria Buonomo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/ecampania.it\/magazine\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/60bf670655ae5494290bd8c5b3e5b16014ed2d0e63339125236db77733732561?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/60bf670655ae5494290bd8c5b3e5b16014ed2d0e63339125236db77733732561?s=96&d=mm&r=g\",\"caption\":\"Valeria Buonomo\"},\"description\":\"Siate custodi della bellezza e sostenitori appassionati del Napoli!\",\"url\":\"https:\/\/ecampania.it\/magazine\/author\/valeria-buonomo\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Napoli. La Biblioteca Nazionale tra libri e danza - \u00e8campania","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ecampania.it\/magazine\/napoli-la-biblioteca-nazionale-tra-libri-e-danza\/","og_locale":"it_IT","og_type":"article","og_title":"Napoli. La Biblioteca Nazionale tra libri e danza - \u00e8campania","og_description":"La grande Biblioteca di Napoli nelle sale del Palazzo Reale Libri e danza..connubio perfetto. Dove lo troviamo? Nella Biblioteca Nazionale di Napoli con sede, dal 1922, nel Palazzo Reale. Ma, attenzione, la sua origine \u00e8 molto pi\u00f9 antica. Risale al 1798, quando Re Ferdinando IV la trasfer\u00ed da Capodimonte al Palazzo degli Studi (oggi attuale [&hellip;]","og_url":"https:\/\/ecampania.it\/magazine\/napoli-la-biblioteca-nazionale-tra-libri-e-danza\/","og_site_name":"\u00e8campania","article_publisher":"https:\/\/www.facebook.com\/ecampania.it","article_published_time":"2026-02-09T12:11:54+00:00","article_modified_time":"2026-02-09T12:44:09+00:00","og_image":[{"width":2048,"height":1536,"url":"https:\/\/ecampania.it\/magazine\/wp-content\/uploads\/2026\/02\/WhatsApp-Image-2026-02-09-at-12.12.54-3.jpeg","type":"image\/jpeg"}],"author":"Valeria Buonomo","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Valeria Buonomo","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ecampania.it\/magazine\/napoli-la-biblioteca-nazionale-tra-libri-e-danza\/#article","isPartOf":{"@id":"https:\/\/ecampania.it\/magazine\/napoli-la-biblioteca-nazionale-tra-libri-e-danza\/"},"author":{"name":"Valeria Buonomo","@id":"https:\/\/ecampania.it\/magazine\/#\/schema\/person\/d5558105981d882b615d1982be1e3867"},"headline":"Napoli. La Biblioteca Nazionale tra libri e danza","datePublished":"2026-02-09T12:11:54+00:00","dateModified":"2026-02-09T12:44:09+00:00","mainEntityOfPage":{"@id":"https:\/\/ecampania.it\/magazine\/napoli-la-biblioteca-nazionale-tra-libri-e-danza\/"},"wordCount":532,"commentCount":0,"publisher":{"@id":"https:\/\/ecampania.it\/magazine\/#organization"},"image":{"@id":"https:\/\/ecampania.it\/magazine\/napoli-la-biblioteca-nazionale-tra-libri-e-danza\/#primaryimage"},"thumbnailUrl":"https:\/\/ecampania.it\/magazine\/wp-content\/uploads\/2026\/02\/WhatsApp-Image-2026-02-09-at-12.12.54-3.jpeg","keywords":["arte","biblioteca"],"articleSection":["Cultura"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/ecampania.it\/magazine\/napoli-la-biblioteca-nazionale-tra-libri-e-danza\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/ecampania.it\/magazine\/napoli-la-biblioteca-nazionale-tra-libri-e-danza\/","url":"https:\/\/ecampania.it\/magazine\/napoli-la-biblioteca-nazionale-tra-libri-e-danza\/","name":"Napoli. La Biblioteca Nazionale tra libri e danza - \u00e8campania","isPartOf":{"@id":"https:\/\/ecampania.it\/magazine\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ecampania.it\/magazine\/napoli-la-biblioteca-nazionale-tra-libri-e-danza\/#primaryimage"},"image":{"@id":"https:\/\/ecampania.it\/magazine\/napoli-la-biblioteca-nazionale-tra-libri-e-danza\/#primaryimage"},"thumbnailUrl":"https:\/\/ecampania.it\/magazine\/wp-content\/uploads\/2026\/02\/WhatsApp-Image-2026-02-09-at-12.12.54-3.jpeg","datePublished":"2026-02-09T12:11:54+00:00","dateModified":"2026-02-09T12:44:09+00:00","breadcrumb":{"@id":"https:\/\/ecampania.it\/magazine\/napoli-la-biblioteca-nazionale-tra-libri-e-danza\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ecampania.it\/magazine\/napoli-la-biblioteca-nazionale-tra-libri-e-danza\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/ecampania.it\/magazine\/napoli-la-biblioteca-nazionale-tra-libri-e-danza\/#primaryimage","url":"https:\/\/ecampania.it\/magazine\/wp-content\/uploads\/2026\/02\/WhatsApp-Image-2026-02-09-at-12.12.54-3.jpeg","contentUrl":"https:\/\/ecampania.it\/magazine\/wp-content\/uploads\/2026\/02\/WhatsApp-Image-2026-02-09-at-12.12.54-3.jpeg","width":2048,"height":1536},{"@type":"BreadcrumbList","@id":"https:\/\/ecampania.it\/magazine\/napoli-la-biblioteca-nazionale-tra-libri-e-danza\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/ecampania.it\/magazine\/"},{"@type":"ListItem","position":2,"name":"Napoli. La Biblioteca Nazionale tra libri e danza"}]},{"@type":"WebSite","@id":"https:\/\/ecampania.it\/magazine\/#website","url":"https:\/\/ecampania.it\/magazine\/","name":"Ecampania","description":"Il primo portale dedicato al turismo ed alla cultura in Campania","publisher":{"@id":"https:\/\/ecampania.it\/magazine\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ecampania.it\/magazine\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/ecampania.it\/magazine\/#organization","name":"Ecampania","url":"https:\/\/ecampania.it\/magazine\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/ecampania.it\/magazine\/#\/schema\/logo\/image\/","url":"https:\/\/ecampania.it\/magazine\/wp-content\/uploads\/2025\/01\/fb.png","contentUrl":"https:\/\/ecampania.it\/magazine\/wp-content\/uploads\/2025\/01\/fb.png","width":500,"height":500,"caption":"Ecampania"},"image":{"@id":"https:\/\/ecampania.it\/magazine\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ecampania.it","https:\/\/www.instagram.com\/ecampania.it\/"]},{"@type":"Person","@id":"https:\/\/ecampania.it\/magazine\/#\/schema\/person\/d5558105981d882b615d1982be1e3867","name":"Valeria Buonomo","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/ecampania.it\/magazine\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/60bf670655ae5494290bd8c5b3e5b16014ed2d0e63339125236db77733732561?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/60bf670655ae5494290bd8c5b3e5b16014ed2d0e63339125236db77733732561?s=96&d=mm&r=g","caption":"Valeria Buonomo"},"description":"Siate custodi della bellezza e sostenitori appassionati del Napoli!","url":"https:\/\/ecampania.it\/magazine\/author\/valeria-buonomo\/"}]}},"_links":{"self":[{"href":"https:\/\/ecampania.it\/magazine\/wp-json\/wp\/v2\/posts\/7920","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ecampania.it\/magazine\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ecampania.it\/magazine\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ecampania.it\/magazine\/wp-json\/wp\/v2\/users\/31"}],"replies":[{"embeddable":true,"href":"https:\/\/ecampania.it\/magazine\/wp-json\/wp\/v2\/comments?post=7920"}],"version-history":[{"count":2,"href":"https:\/\/ecampania.it\/magazine\/wp-json\/wp\/v2\/posts\/7920\/revisions"}],"predecessor-version":[{"id":7923,"href":"https:\/\/ecampania.it\/magazine\/wp-json\/wp\/v2\/posts\/7920\/revisions\/7923"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ecampania.it\/magazine\/wp-json\/wp\/v2\/media\/7921"}],"wp:attachment":[{"href":"https:\/\/ecampania.it\/magazine\/wp-json\/wp\/v2\/media?parent=7920"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ecampania.it\/magazine\/wp-json\/wp\/v2\/categories?post=7920"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ecampania.it\/magazine\/wp-json\/wp\/v2\/tags?post=7920"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}