{"id":8717,"date":"2026-03-23T11:51:48","date_gmt":"2026-03-23T10:51:48","guid":{"rendered":"https:\/\/ecampania.it\/magazine\/?p=8717"},"modified":"2026-03-23T11:51:48","modified_gmt":"2026-03-23T10:51:48","slug":"al-cilea-carlo-buccirosso-con-la-commedia-l-erba-del-vicino-e-sempre-piu-verde","status":"publish","type":"post","link":"https:\/\/ecampania.it\/magazine\/al-cilea-carlo-buccirosso-con-la-commedia-l-erba-del-vicino-e-sempre-piu-verde\/","title":{"rendered":"Al Cilea Carlo Buccirosso con la commedia &#8220;L&#8217;erba del vicino \u00e8 sempre pi\u00f9 verde&#8221;"},"content":{"rendered":"\n<p><strong><em>Dal 26 al 29 marzo in scena l\u2019 esilarante commedia del maestro della comicit\u00e0 partenopea<\/em><\/strong><\/p>\n\n\n\n<p>La stagione teatrale 2025\/2026 del <strong>Teatro Cilea<\/strong> di Napoli prosegue con uno degli interpreti pi\u00f9 amati e versatili del panorama artistico italiano. Da <strong>giovedi 26 a sabato 29 marzo<\/strong>, il palcoscenico del teatro vomerese verr\u00e0 calcato da <strong>Carlo Buccirosso <\/strong>con la sua commedia \u201c<strong>L\u2019erba del vicino \u00e8 sempre pi\u00f9 verde<\/strong>\u201d, un testo brillante che porta con s\u00e9 la firma inconfondibile dell\u2019attore, regista e commediografo partenopeo.<\/p>\n\n\n\n<p>Dopo i trionfi di pubblico e critica che hanno visto protagonisti di questi primi mesi dell\u2019anno artisti del calibro di Francesco Cicchella, Lina Sastri, Eduardo Tartaglia e Paolo Caiazzo, il Cilea conferma la sua vocazione di tempio della grande drammaturgia campana, accogliendo ora Buccirosso, reduce da una carriera costellata di successi che spaziano dal teatro al cinema.<\/p>\n\n\n\n<p>Volto noto al grande pubblico per le sue collaborazioni con Vincenzo Salemme, Paolo Sorrentino e per l\u2019indimenticabile partecipazione a \u201cNoi e la Giulia\u201d di Edoardo Leo \u2013 ruolo che gli \u00e8 valso il David di Donatello come miglior attore non protagonista \u2013 Buccirosso ha saputo negli anni conquistare generazioni di spettatori grazie a una comicit\u00e0 sofisticata, capace di mescolare la tradizione della sceneggiata napoletana con i meccanismi perfetti della commedia degli equivoci.<\/p>\n\n\n\n<p>Ad affiancarlo sul palco un cast d\u2019eccezione: <strong>Fabrizio Miano<\/strong>, <strong>Donatella De Felice,<\/strong> <strong>Peppe Miale<\/strong>, <strong>Elvira Zingone<\/strong>, <strong>Maria Bolignano<\/strong> e <strong>Fiorella Zullo<\/strong>.<\/p>\n\n\n\n<p>LA TRAMA<\/p>\n\n\n\n<p>Al centro della scena c\u2019\u00e8 Mario Martusciello (Buccirosso), funzionario di banca benestante ma in piena crisi esistenziale. Dopo una burrascosa separazione dalla moglie, Mario vive ormai da mesi in un moderno monolocale, sprofondato in una depressione che lo porta a guardare con invidia e desiderio tutto ci\u00f2 che non gli appartiene: vite diverse, emozioni nuove, persone sconosciute.<\/p>\n\n\n\n<p>La sua spasmodica ricerca di libert\u00e0 e di cambiamento lo porta a idealizzare chiunque sia diverso da s\u00e9, a cominciare da una giovane e avvenente influencer incontrata per caso. In questo clima di confusione e autocommiserazione, chiunque bussi alla sua porta \u2013 che sia per consegnare una cena giapponese, un pacco postale o, peggio ancora, per un errore di domicilio \u2013 rischia di rimanere invischiato in una situazione paradossale e sempre pi\u00f9 fuori controllo.<\/p>\n\n\n\n<p>Ma cosa accadrebbe se a suonare fosse proprio il vicino di casa in carne e ossa, magari solo per chiedere qualche foglia di prezzemolo? La sindrome dell\u2019 \u201cerba del vicino\u201d si macchier\u00e0 di rosso sangue o regaler\u00e0 un finale a sorpresa?<\/p>\n\n\n\n<p>NOTE DI REGIA<\/p>\n\n\n\n<p>Scritta e diretta da Carlo Buccirosso, la commedia indaga con ironia tagliente e tempi comici perfetti le nevrosi dell\u2019uomo contemporaneo, la sua perenne insoddisfazione e la tendenza a sopravvalutare ci\u00f2 che non si ha. Un meccanismo teatrale rodatissimo, che trascina lo spettatore in un vortice di risate e colpi di scena, senza mai perdere di vista la profondit\u00e0 dei personaggi.<\/p>\n\n\n\n<p><strong>Biglietti<\/strong>: gioved\u00ec 28 euro platea e 23 euro galleria, venerd\u00ec, sabato e domenica platea 33 euro e galleria 28 euro.<br><strong>Inizio spettacolo<\/strong>: ore 21 tranne la domenica ore 18.<br><strong>Prevendite<\/strong>:<br><a href=\"https:\/\/teatrocilea.it\/spettacoli\/carlo-buccirosso-l-erba-del-vicino-e-sempre-piu-verde\/\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/teatrocilea.it\/spettacoli\/carlo-buccirosso-l-erba-del-vicino-e-sempre-piu-verde\/<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dal 26 al 29 marzo in scena l\u2019 esilarante commedia del maestro della comicit\u00e0 partenopea La stagione teatrale 2025\/2026 del Teatro Cilea di Napoli prosegue con uno degli interpreti pi\u00f9 amati e versatili del panorama artistico italiano. Da giovedi 26 a sabato 29 marzo, il palcoscenico del teatro vomerese verr\u00e0 calcato da Carlo Buccirosso con [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":8718,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jnews-multi-image_gallery":[],"jnews_single_post":{"format":"standard"},"jnews_primary_category":[],"jnews_override_counter":[],"footnotes":""},"categories":[8],"tags":[28],"class_list":["post-8717","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura","tag-prima"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Al Cilea Carlo Buccirosso con la commedia &quot;L&#039;erba del vicino \u00e8 sempre pi\u00f9 verde&quot; - \u00e8campania<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ecampania.it\/magazine\/al-cilea-carlo-buccirosso-con-la-commedia-l-erba-del-vicino-e-sempre-piu-verde\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Al Cilea Carlo Buccirosso con la commedia &quot;L&#039;erba del vicino \u00e8 sempre pi\u00f9 verde&quot; - \u00e8campania\" \/>\n<meta property=\"og:description\" content=\"Dal 26 al 29 marzo in scena l\u2019 esilarante commedia del maestro della comicit\u00e0 partenopea La stagione teatrale 2025\/2026 del Teatro Cilea di Napoli prosegue con uno degli interpreti pi\u00f9 amati e versatili del panorama artistico italiano. Da giovedi 26 a sabato 29 marzo, il palcoscenico del teatro vomerese verr\u00e0 calcato da Carlo Buccirosso con [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ecampania.it\/magazine\/al-cilea-carlo-buccirosso-con-la-commedia-l-erba-del-vicino-e-sempre-piu-verde\/\" \/>\n<meta property=\"og:site_name\" content=\"\u00e8campania\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ecampania.it\" \/>\n<meta property=\"article:published_time\" content=\"2026-03-23T10:51:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ecampania.it\/magazine\/wp-content\/uploads\/2026\/03\/buccirosso2526-cover_2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"450\" \/>\n\t<meta property=\"og:image:height\" content=\"629\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/ecampania.it\/magazine\/al-cilea-carlo-buccirosso-con-la-commedia-l-erba-del-vicino-e-sempre-piu-verde\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/ecampania.it\/magazine\/al-cilea-carlo-buccirosso-con-la-commedia-l-erba-del-vicino-e-sempre-piu-verde\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\/\/ecampania.it\/magazine\/#\/schema\/person\/f259cd7c01428ef3ac5db31dcac5ab70\"},\"headline\":\"Al Cilea Carlo Buccirosso con la commedia &#8220;L&#8217;erba del vicino \u00e8 sempre pi\u00f9 verde&#8221;\",\"datePublished\":\"2026-03-23T10:51:48+00:00\",\"dateModified\":\"2026-03-23T10:51:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/ecampania.it\/magazine\/al-cilea-carlo-buccirosso-con-la-commedia-l-erba-del-vicino-e-sempre-piu-verde\/\"},\"wordCount\":504,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/ecampania.it\/magazine\/#organization\"},\"image\":{\"@id\":\"https:\/\/ecampania.it\/magazine\/al-cilea-carlo-buccirosso-con-la-commedia-l-erba-del-vicino-e-sempre-piu-verde\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/ecampania.it\/magazine\/wp-content\/uploads\/2026\/03\/buccirosso2526-cover_2.jpg\",\"keywords\":[\"prima\"],\"articleSection\":[\"Cultura\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/ecampania.it\/magazine\/al-cilea-carlo-buccirosso-con-la-commedia-l-erba-del-vicino-e-sempre-piu-verde\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ecampania.it\/magazine\/al-cilea-carlo-buccirosso-con-la-commedia-l-erba-del-vicino-e-sempre-piu-verde\/\",\"url\":\"https:\/\/ecampania.it\/magazine\/al-cilea-carlo-buccirosso-con-la-commedia-l-erba-del-vicino-e-sempre-piu-verde\/\",\"name\":\"Al Cilea Carlo Buccirosso con la commedia \\\"L'erba del vicino \u00e8 sempre pi\u00f9 verde\\\" - \u00e8campania\",\"isPartOf\":{\"@id\":\"https:\/\/ecampania.it\/magazine\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/ecampania.it\/magazine\/al-cilea-carlo-buccirosso-con-la-commedia-l-erba-del-vicino-e-sempre-piu-verde\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/ecampania.it\/magazine\/al-cilea-carlo-buccirosso-con-la-commedia-l-erba-del-vicino-e-sempre-piu-verde\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/ecampania.it\/magazine\/wp-content\/uploads\/2026\/03\/buccirosso2526-cover_2.jpg\",\"datePublished\":\"2026-03-23T10:51:48+00:00\",\"dateModified\":\"2026-03-23T10:51:48+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/ecampania.it\/magazine\/al-cilea-carlo-buccirosso-con-la-commedia-l-erba-del-vicino-e-sempre-piu-verde\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ecampania.it\/magazine\/al-cilea-carlo-buccirosso-con-la-commedia-l-erba-del-vicino-e-sempre-piu-verde\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/ecampania.it\/magazine\/al-cilea-carlo-buccirosso-con-la-commedia-l-erba-del-vicino-e-sempre-piu-verde\/#primaryimage\",\"url\":\"https:\/\/ecampania.it\/magazine\/wp-content\/uploads\/2026\/03\/buccirosso2526-cover_2.jpg\",\"contentUrl\":\"https:\/\/ecampania.it\/magazine\/wp-content\/uploads\/2026\/03\/buccirosso2526-cover_2.jpg\",\"width\":450,\"height\":629},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ecampania.it\/magazine\/al-cilea-carlo-buccirosso-con-la-commedia-l-erba-del-vicino-e-sempre-piu-verde\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/ecampania.it\/magazine\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Al Cilea Carlo Buccirosso con la commedia &#8220;L&#8217;erba del vicino \u00e8 sempre pi\u00f9 verde&#8221;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ecampania.it\/magazine\/#website\",\"url\":\"https:\/\/ecampania.it\/magazine\/\",\"name\":\"Ecampania\",\"description\":\"Il primo portale dedicato al turismo ed alla cultura in Campania\",\"publisher\":{\"@id\":\"https:\/\/ecampania.it\/magazine\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ecampania.it\/magazine\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/ecampania.it\/magazine\/#organization\",\"name\":\"Ecampania\",\"url\":\"https:\/\/ecampania.it\/magazine\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/ecampania.it\/magazine\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/ecampania.it\/magazine\/wp-content\/uploads\/2025\/01\/fb.png\",\"contentUrl\":\"https:\/\/ecampania.it\/magazine\/wp-content\/uploads\/2025\/01\/fb.png\",\"width\":500,\"height\":500,\"caption\":\"Ecampania\"},\"image\":{\"@id\":\"https:\/\/ecampania.it\/magazine\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/ecampania.it\",\"https:\/\/www.instagram.com\/ecampania.it\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/ecampania.it\/magazine\/#\/schema\/person\/f259cd7c01428ef3ac5db31dcac5ab70\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/ecampania.it\/magazine\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/95816d083b7410def6d31c027c3ddb4f82515f84e68ea358ea75203bfac610a7?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/95816d083b7410def6d31c027c3ddb4f82515f84e68ea358ea75203bfac610a7?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\/\/ecampania.it\/magazine\/author\/ecampania\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Al Cilea Carlo Buccirosso con la commedia \"L'erba del vicino \u00e8 sempre pi\u00f9 verde\" - \u00e8campania","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ecampania.it\/magazine\/al-cilea-carlo-buccirosso-con-la-commedia-l-erba-del-vicino-e-sempre-piu-verde\/","og_locale":"it_IT","og_type":"article","og_title":"Al Cilea Carlo Buccirosso con la commedia \"L'erba del vicino \u00e8 sempre pi\u00f9 verde\" - \u00e8campania","og_description":"Dal 26 al 29 marzo in scena l\u2019 esilarante commedia del maestro della comicit\u00e0 partenopea La stagione teatrale 2025\/2026 del Teatro Cilea di Napoli prosegue con uno degli interpreti pi\u00f9 amati e versatili del panorama artistico italiano. Da giovedi 26 a sabato 29 marzo, il palcoscenico del teatro vomerese verr\u00e0 calcato da Carlo Buccirosso con [&hellip;]","og_url":"https:\/\/ecampania.it\/magazine\/al-cilea-carlo-buccirosso-con-la-commedia-l-erba-del-vicino-e-sempre-piu-verde\/","og_site_name":"\u00e8campania","article_publisher":"https:\/\/www.facebook.com\/ecampania.it","article_published_time":"2026-03-23T10:51:48+00:00","og_image":[{"width":450,"height":629,"url":"https:\/\/ecampania.it\/magazine\/wp-content\/uploads\/2026\/03\/buccirosso2526-cover_2.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ecampania.it\/magazine\/al-cilea-carlo-buccirosso-con-la-commedia-l-erba-del-vicino-e-sempre-piu-verde\/#article","isPartOf":{"@id":"https:\/\/ecampania.it\/magazine\/al-cilea-carlo-buccirosso-con-la-commedia-l-erba-del-vicino-e-sempre-piu-verde\/"},"author":{"name":"Redazione","@id":"https:\/\/ecampania.it\/magazine\/#\/schema\/person\/f259cd7c01428ef3ac5db31dcac5ab70"},"headline":"Al Cilea Carlo Buccirosso con la commedia &#8220;L&#8217;erba del vicino \u00e8 sempre pi\u00f9 verde&#8221;","datePublished":"2026-03-23T10:51:48+00:00","dateModified":"2026-03-23T10:51:48+00:00","mainEntityOfPage":{"@id":"https:\/\/ecampania.it\/magazine\/al-cilea-carlo-buccirosso-con-la-commedia-l-erba-del-vicino-e-sempre-piu-verde\/"},"wordCount":504,"commentCount":0,"publisher":{"@id":"https:\/\/ecampania.it\/magazine\/#organization"},"image":{"@id":"https:\/\/ecampania.it\/magazine\/al-cilea-carlo-buccirosso-con-la-commedia-l-erba-del-vicino-e-sempre-piu-verde\/#primaryimage"},"thumbnailUrl":"https:\/\/ecampania.it\/magazine\/wp-content\/uploads\/2026\/03\/buccirosso2526-cover_2.jpg","keywords":["prima"],"articleSection":["Cultura"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/ecampania.it\/magazine\/al-cilea-carlo-buccirosso-con-la-commedia-l-erba-del-vicino-e-sempre-piu-verde\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/ecampania.it\/magazine\/al-cilea-carlo-buccirosso-con-la-commedia-l-erba-del-vicino-e-sempre-piu-verde\/","url":"https:\/\/ecampania.it\/magazine\/al-cilea-carlo-buccirosso-con-la-commedia-l-erba-del-vicino-e-sempre-piu-verde\/","name":"Al Cilea Carlo Buccirosso con la commedia \"L'erba del vicino \u00e8 sempre pi\u00f9 verde\" - \u00e8campania","isPartOf":{"@id":"https:\/\/ecampania.it\/magazine\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ecampania.it\/magazine\/al-cilea-carlo-buccirosso-con-la-commedia-l-erba-del-vicino-e-sempre-piu-verde\/#primaryimage"},"image":{"@id":"https:\/\/ecampania.it\/magazine\/al-cilea-carlo-buccirosso-con-la-commedia-l-erba-del-vicino-e-sempre-piu-verde\/#primaryimage"},"thumbnailUrl":"https:\/\/ecampania.it\/magazine\/wp-content\/uploads\/2026\/03\/buccirosso2526-cover_2.jpg","datePublished":"2026-03-23T10:51:48+00:00","dateModified":"2026-03-23T10:51:48+00:00","breadcrumb":{"@id":"https:\/\/ecampania.it\/magazine\/al-cilea-carlo-buccirosso-con-la-commedia-l-erba-del-vicino-e-sempre-piu-verde\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ecampania.it\/magazine\/al-cilea-carlo-buccirosso-con-la-commedia-l-erba-del-vicino-e-sempre-piu-verde\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/ecampania.it\/magazine\/al-cilea-carlo-buccirosso-con-la-commedia-l-erba-del-vicino-e-sempre-piu-verde\/#primaryimage","url":"https:\/\/ecampania.it\/magazine\/wp-content\/uploads\/2026\/03\/buccirosso2526-cover_2.jpg","contentUrl":"https:\/\/ecampania.it\/magazine\/wp-content\/uploads\/2026\/03\/buccirosso2526-cover_2.jpg","width":450,"height":629},{"@type":"BreadcrumbList","@id":"https:\/\/ecampania.it\/magazine\/al-cilea-carlo-buccirosso-con-la-commedia-l-erba-del-vicino-e-sempre-piu-verde\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/ecampania.it\/magazine\/"},{"@type":"ListItem","position":2,"name":"Al Cilea Carlo Buccirosso con la commedia &#8220;L&#8217;erba del vicino \u00e8 sempre pi\u00f9 verde&#8221;"}]},{"@type":"WebSite","@id":"https:\/\/ecampania.it\/magazine\/#website","url":"https:\/\/ecampania.it\/magazine\/","name":"Ecampania","description":"Il primo portale dedicato al turismo ed alla cultura in Campania","publisher":{"@id":"https:\/\/ecampania.it\/magazine\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ecampania.it\/magazine\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/ecampania.it\/magazine\/#organization","name":"Ecampania","url":"https:\/\/ecampania.it\/magazine\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/ecampania.it\/magazine\/#\/schema\/logo\/image\/","url":"https:\/\/ecampania.it\/magazine\/wp-content\/uploads\/2025\/01\/fb.png","contentUrl":"https:\/\/ecampania.it\/magazine\/wp-content\/uploads\/2025\/01\/fb.png","width":500,"height":500,"caption":"Ecampania"},"image":{"@id":"https:\/\/ecampania.it\/magazine\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ecampania.it","https:\/\/www.instagram.com\/ecampania.it\/"]},{"@type":"Person","@id":"https:\/\/ecampania.it\/magazine\/#\/schema\/person\/f259cd7c01428ef3ac5db31dcac5ab70","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/ecampania.it\/magazine\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/95816d083b7410def6d31c027c3ddb4f82515f84e68ea358ea75203bfac610a7?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/95816d083b7410def6d31c027c3ddb4f82515f84e68ea358ea75203bfac610a7?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/ecampania.it\/magazine\/author\/ecampania\/"}]}},"_links":{"self":[{"href":"https:\/\/ecampania.it\/magazine\/wp-json\/wp\/v2\/posts\/8717","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ecampania.it\/magazine\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ecampania.it\/magazine\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ecampania.it\/magazine\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/ecampania.it\/magazine\/wp-json\/wp\/v2\/comments?post=8717"}],"version-history":[{"count":1,"href":"https:\/\/ecampania.it\/magazine\/wp-json\/wp\/v2\/posts\/8717\/revisions"}],"predecessor-version":[{"id":8720,"href":"https:\/\/ecampania.it\/magazine\/wp-json\/wp\/v2\/posts\/8717\/revisions\/8720"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ecampania.it\/magazine\/wp-json\/wp\/v2\/media\/8718"}],"wp:attachment":[{"href":"https:\/\/ecampania.it\/magazine\/wp-json\/wp\/v2\/media?parent=8717"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ecampania.it\/magazine\/wp-json\/wp\/v2\/categories?post=8717"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ecampania.it\/magazine\/wp-json\/wp\/v2\/tags?post=8717"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}