{"id":8788,"date":"2026-03-26T17:45:27","date_gmt":"2026-03-26T16:45:27","guid":{"rendered":"https:\/\/ecampania.it\/magazine\/?p=8788"},"modified":"2026-03-26T18:00:15","modified_gmt":"2026-03-26T17:00:15","slug":"caserta-alla-gelateria-la-fenice-la-primavera-e-all-insegna-dei-gelati-anni-80","status":"publish","type":"post","link":"https:\/\/ecampania.it\/magazine\/caserta-alla-gelateria-la-fenice-la-primavera-e-all-insegna-dei-gelati-anni-80\/","title":{"rendered":"Caserta, alla gelateria La Fenice la primavera \u00e8 all\u2019insegna dei gelati anni \u201980"},"content":{"rendered":"\n<h4 class=\"wp-block-heading\">I gusti rivisitati dalla maestra gelatiera Pina Molitierno<\/h4>\n\n\n\n<p>Alla gelateria <strong>La Fenice di Caserta<\/strong> la primavera \u00e8 all\u2019insegna dei gelati che hanno fatto la storia di questo piacere dalla vita e che nel tempo sono stati un po\u2019 dimenticati. Accanto alla ricca proposta di gusti classici la maestra gelatiera <strong>Pina Molitierno<\/strong> ha deciso di dedicare un\u2019altra sezione della vetrina ai <strong>gelati degli anni \u201980<\/strong>, amatissimi non solo dai dai boomer e dalla generazione X ma anche dai pi\u00f9 giovani.<\/p>\n\n\n\n<p><strong>A partire<\/strong> <strong>dal 26 marzo<\/strong> spazio, quindi, a <strong>Blob <\/strong>(g<em>elato al caramello variegato al cioccolato, con arachidi salate e salsa al caramello<\/em>), <strong>Camillino <\/strong>(g<em>elato allo zabaione tra biscotti alla vaniglia<\/em>), <strong>Coppa Rica al caff\u00e8 <\/strong>(<em>gelato al caff\u00e8, variegato al cioccolato fondente, salsa al caff\u00e8, granelle di nocciole e meringhe<\/em>), <strong>Coppa Rica alla vaniglia <\/strong>(<em>gelato alla vaniglia, variegato con salsa al cioccolato, granella di meringhe e nocciole pralinate tartufate<\/em>)<strong>Coppa Rica spagnola <\/strong>(g<em>elato alla crema variegato all&#8217;amarena<\/em>)<em>, <\/em><strong>Cornetto classico <\/strong>(<em>gelato alla stracciatella con cioccolato fondente peruviano, granella di nocciola e cialda croccante<\/em>)<em>, <\/em><strong>Croccante all&#8217;amarena <\/strong>(<em>gelato al fiordilatte, variegato con cioccolato fondente, amarene, granella di nocciole e meringhe, <\/em><strong>Gran Rico al whisky <\/strong>(<em>gelato al whisky Chivas Regal, con cioccolato fondente, uvetta bagnata nel whisky e salsa al whisky<\/em>) e<strong>Winner Taco <\/strong>(<em>gelato fiordilatte alla vaniglia, variegato con arachidi salate, cialda croccante, salsa al caramello e al cioccolato fondente<\/em>). I gusti saranno disponibili a rotazione per l\u2019intera primavera.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"8790\" src=\"https:\/\/ecampania.it\/magazine\/wp-content\/uploads\/2026\/03\/20260325_181101-1024x768.jpg\" alt=\"\" class=\"wp-image-8790\" srcset=\"https:\/\/ecampania.it\/magazine\/wp-content\/uploads\/2026\/03\/20260325_181101-1024x768.jpg 1024w, https:\/\/ecampania.it\/magazine\/wp-content\/uploads\/2026\/03\/20260325_181101-300x225.jpg 300w, https:\/\/ecampania.it\/magazine\/wp-content\/uploads\/2026\/03\/20260325_181101-768x576.jpg 768w, https:\/\/ecampania.it\/magazine\/wp-content\/uploads\/2026\/03\/20260325_181101-750x562.jpg 750w, https:\/\/ecampania.it\/magazine\/wp-content\/uploads\/2026\/03\/20260325_181101.jpg 1103w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"8791\" src=\"https:\/\/ecampania.it\/magazine\/wp-content\/uploads\/2026\/03\/20260325_181121-1024x768.jpg\" alt=\"\" class=\"wp-image-8791\" srcset=\"https:\/\/ecampania.it\/magazine\/wp-content\/uploads\/2026\/03\/20260325_181121-1024x768.jpg 1024w, https:\/\/ecampania.it\/magazine\/wp-content\/uploads\/2026\/03\/20260325_181121-300x225.jpg 300w, https:\/\/ecampania.it\/magazine\/wp-content\/uploads\/2026\/03\/20260325_181121-768x576.jpg 768w, https:\/\/ecampania.it\/magazine\/wp-content\/uploads\/2026\/03\/20260325_181121-750x562.jpg 750w, https:\/\/ecampania.it\/magazine\/wp-content\/uploads\/2026\/03\/20260325_181121.jpg 1103w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-2 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"620\" height=\"827\" data-id=\"8792\" src=\"https:\/\/ecampania.it\/magazine\/wp-content\/uploads\/2026\/03\/20230706_222131.jpg\" alt=\"\" class=\"wp-image-8792\" srcset=\"https:\/\/ecampania.it\/magazine\/wp-content\/uploads\/2026\/03\/20230706_222131.jpg 620w, https:\/\/ecampania.it\/magazine\/wp-content\/uploads\/2026\/03\/20230706_222131-225x300.jpg 225w\" sizes=\"(max-width: 620px) 100vw, 620px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"8793\" src=\"https:\/\/ecampania.it\/magazine\/wp-content\/uploads\/2026\/03\/20260325_175850-1-1024x768.jpg\" alt=\"\" class=\"wp-image-8793\" srcset=\"https:\/\/ecampania.it\/magazine\/wp-content\/uploads\/2026\/03\/20260325_175850-1-1024x768.jpg 1024w, https:\/\/ecampania.it\/magazine\/wp-content\/uploads\/2026\/03\/20260325_175850-1-300x225.jpg 300w, https:\/\/ecampania.it\/magazine\/wp-content\/uploads\/2026\/03\/20260325_175850-1-768x576.jpg 768w, https:\/\/ecampania.it\/magazine\/wp-content\/uploads\/2026\/03\/20260325_175850-1-750x562.jpg 750w, https:\/\/ecampania.it\/magazine\/wp-content\/uploads\/2026\/03\/20260325_175850-1.jpg 1103w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>\n\n\n\n<p><strong>La Fenice<\/strong><br>La maestra gelatiera Pina Molitierno apre nel centralissimo corso Trieste di Caserta\u00a0 \u201cLa Fenice Gelateria &amp; Yogurteria Artigianale\u201d il 4 luglio del 2023. Non casuale la scelta del nome del locale perch\u00e9 il ritorno sulle scene della Molitierno avviene esattamente allo stesso indirizzo in cui si era gi\u00e0 fatta apprezzare con la gelateria \u201cVanilla Ice\u201d, chiusa per una serie di circostanze avverse. Ad affiancarla in questa rinascita imprenditoriale \u00e8 il dottore Giuseppe Molfino, stimato oculista casertano.<br>Materie prime selezionate in modo quasi maniacale e produzione a basso impatto ambientale grazie alla scelta di macchinari di ultima generazione che permettono un risparmio idrico ed energetico del 40% rispetto ai macchinari tradizionali. A ridurre ulteriormente i consumi energetici anche l\u2019impiego di quantit\u00e0 di zucchero pi\u00f9 ridotte con cui \u00e8 possibile tenere meno bassa la temperatura della vetrina.\u00a0<br>Trentasei vaschette con altrettanti gusti che spaziano da quelli tradizionalissimi, qui realizzati con le migliori materie prime disponibili sul mercato, a quelli gastronomici che cambiano di frequente. Gusto esclusivo de La Fenice \u00e8 il \u201cBuffoncello\u201d reallizzato con latte di bufala e limoncello.<br>Nel 2024 La Fenice fa il suo ingresso nella guida delle Gelaterie d\u2019Italia del Gambero Rosso con 1 cono.<\/p>\n\n\n\n<p><strong>Pina Molitierno<\/strong><br>Nasce ad Aversa e si appassiona giovanissima alla cucina, sempre alla ricerca di tecniche ed ingredienti ottimali per la realizzazione delle ricette. Nel 2009, riesce a coronare il sogno di una gelateria propria ed affina le sue competenze seguendo numerosi corsi di aggiornamento di gelateria, pasticceria e cioccolateria con il gotha dei professionisti del settore: Rolando Morandin, Gino Fabbri, Rossano Vinciarelli, Mario Morri, Carola Stacchezzini, Christian Beduschi, Luca Montersino, Paolo Cappellini, Giampaolo Valli.<br>Nel 2014 entra nella classifica delle 100 gelaterie artigianali migliori d\u2019Italia su Dissapore e rappresenta la Campania nell\u2019edizione di \u201cGelati d\u2019Italia\u201d ad Orvieto; negli anni tiene lezioni didattiche e partecipa a trasmissioni televisive, su reti nazionali, per parlare del gelato come nutrimento funzionale.<br>Nel 2015 vince il premio della giuria tecnica, al \u201cGelato festival\u201d di Napoli e partecipa all&#8217;Expo di Milano; nel 2016 partecipa con la Conpait gelato al Sigep di Rimini, dove una sua ricetta di gelato al mascarpone di bufala viene inserita nel libro &#8220;La dolce Italia&#8221;.<\/p>\n\n\n\n<p><strong>La Fenice Gelateria &amp; Yogurteria Artigianale<\/strong><br>Corso Trieste, 147<br>Caserta<br>Tel. 375 8117654<\/p>\n","protected":false},"excerpt":{"rendered":"<p>I gusti rivisitati dalla maestra gelatiera Pina Molitierno Alla gelateria La Fenice di Caserta la primavera \u00e8 all\u2019insegna dei gelati che hanno fatto la storia di questo piacere dalla vita e che nel tempo sono stati un po\u2019 dimenticati. Accanto alla ricca proposta di gusti classici la maestra gelatiera Pina Molitierno ha deciso di dedicare [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":8795,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jnews-multi-image_gallery":[],"jnews_single_post":{"format":"standard"},"jnews_primary_category":[],"jnews_override_counter":[],"footnotes":""},"categories":[9],"tags":[28],"class_list":["post-8788","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-food","tag-prima"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Caserta, alla gelateria La Fenice la primavera \u00e8 all\u2019insegna dei gelati anni \u201980 - \u00e8campania<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ecampania.it\/magazine\/caserta-alla-gelateria-la-fenice-la-primavera-e-all-insegna-dei-gelati-anni-80\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Caserta, alla gelateria La Fenice la primavera \u00e8 all\u2019insegna dei gelati anni \u201980 - \u00e8campania\" \/>\n<meta property=\"og:description\" content=\"I gusti rivisitati dalla maestra gelatiera Pina Molitierno Alla gelateria La Fenice di Caserta la primavera \u00e8 all\u2019insegna dei gelati che hanno fatto la storia di questo piacere dalla vita e che nel tempo sono stati un po\u2019 dimenticati. Accanto alla ricca proposta di gusti classici la maestra gelatiera Pina Molitierno ha deciso di dedicare [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ecampania.it\/magazine\/caserta-alla-gelateria-la-fenice-la-primavera-e-all-insegna-dei-gelati-anni-80\/\" \/>\n<meta property=\"og:site_name\" content=\"\u00e8campania\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ecampania.it\" \/>\n<meta property=\"article:published_time\" content=\"2026-03-26T16:45:27+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-26T17:00:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ecampania.it\/magazine\/wp-content\/uploads\/2026\/03\/la-fenice-caserta.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1103\" \/>\n\t<meta property=\"og:image:height\" content=\"827\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/ecampania.it\/magazine\/caserta-alla-gelateria-la-fenice-la-primavera-e-all-insegna-dei-gelati-anni-80\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/ecampania.it\/magazine\/caserta-alla-gelateria-la-fenice-la-primavera-e-all-insegna-dei-gelati-anni-80\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\/\/ecampania.it\/magazine\/#\/schema\/person\/f259cd7c01428ef3ac5db31dcac5ab70\"},\"headline\":\"Caserta, alla gelateria La Fenice la primavera \u00e8 all\u2019insegna dei gelati anni \u201980\",\"datePublished\":\"2026-03-26T16:45:27+00:00\",\"dateModified\":\"2026-03-26T17:00:15+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/ecampania.it\/magazine\/caserta-alla-gelateria-la-fenice-la-primavera-e-all-insegna-dei-gelati-anni-80\/\"},\"wordCount\":608,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/ecampania.it\/magazine\/#organization\"},\"image\":{\"@id\":\"https:\/\/ecampania.it\/magazine\/caserta-alla-gelateria-la-fenice-la-primavera-e-all-insegna-dei-gelati-anni-80\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/ecampania.it\/magazine\/wp-content\/uploads\/2026\/03\/la-fenice-caserta.jpg\",\"keywords\":[\"prima\"],\"articleSection\":[\"Food\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/ecampania.it\/magazine\/caserta-alla-gelateria-la-fenice-la-primavera-e-all-insegna-dei-gelati-anni-80\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ecampania.it\/magazine\/caserta-alla-gelateria-la-fenice-la-primavera-e-all-insegna-dei-gelati-anni-80\/\",\"url\":\"https:\/\/ecampania.it\/magazine\/caserta-alla-gelateria-la-fenice-la-primavera-e-all-insegna-dei-gelati-anni-80\/\",\"name\":\"Caserta, alla gelateria La Fenice la primavera \u00e8 all\u2019insegna dei gelati anni \u201980 - \u00e8campania\",\"isPartOf\":{\"@id\":\"https:\/\/ecampania.it\/magazine\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/ecampania.it\/magazine\/caserta-alla-gelateria-la-fenice-la-primavera-e-all-insegna-dei-gelati-anni-80\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/ecampania.it\/magazine\/caserta-alla-gelateria-la-fenice-la-primavera-e-all-insegna-dei-gelati-anni-80\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/ecampania.it\/magazine\/wp-content\/uploads\/2026\/03\/la-fenice-caserta.jpg\",\"datePublished\":\"2026-03-26T16:45:27+00:00\",\"dateModified\":\"2026-03-26T17:00:15+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/ecampania.it\/magazine\/caserta-alla-gelateria-la-fenice-la-primavera-e-all-insegna-dei-gelati-anni-80\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ecampania.it\/magazine\/caserta-alla-gelateria-la-fenice-la-primavera-e-all-insegna-dei-gelati-anni-80\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/ecampania.it\/magazine\/caserta-alla-gelateria-la-fenice-la-primavera-e-all-insegna-dei-gelati-anni-80\/#primaryimage\",\"url\":\"https:\/\/ecampania.it\/magazine\/wp-content\/uploads\/2026\/03\/la-fenice-caserta.jpg\",\"contentUrl\":\"https:\/\/ecampania.it\/magazine\/wp-content\/uploads\/2026\/03\/la-fenice-caserta.jpg\",\"width\":1103,\"height\":827},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ecampania.it\/magazine\/caserta-alla-gelateria-la-fenice-la-primavera-e-all-insegna-dei-gelati-anni-80\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/ecampania.it\/magazine\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Caserta, alla gelateria La Fenice la primavera \u00e8 all\u2019insegna dei gelati anni \u201980\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ecampania.it\/magazine\/#website\",\"url\":\"https:\/\/ecampania.it\/magazine\/\",\"name\":\"Ecampania\",\"description\":\"Il primo portale dedicato al turismo ed alla cultura in Campania\",\"publisher\":{\"@id\":\"https:\/\/ecampania.it\/magazine\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ecampania.it\/magazine\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/ecampania.it\/magazine\/#organization\",\"name\":\"Ecampania\",\"url\":\"https:\/\/ecampania.it\/magazine\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/ecampania.it\/magazine\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/ecampania.it\/magazine\/wp-content\/uploads\/2025\/01\/fb.png\",\"contentUrl\":\"https:\/\/ecampania.it\/magazine\/wp-content\/uploads\/2025\/01\/fb.png\",\"width\":500,\"height\":500,\"caption\":\"Ecampania\"},\"image\":{\"@id\":\"https:\/\/ecampania.it\/magazine\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/ecampania.it\",\"https:\/\/www.instagram.com\/ecampania.it\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/ecampania.it\/magazine\/#\/schema\/person\/f259cd7c01428ef3ac5db31dcac5ab70\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/ecampania.it\/magazine\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/95816d083b7410def6d31c027c3ddb4f82515f84e68ea358ea75203bfac610a7?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/95816d083b7410def6d31c027c3ddb4f82515f84e68ea358ea75203bfac610a7?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\/\/ecampania.it\/magazine\/author\/ecampania\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Caserta, alla gelateria La Fenice la primavera \u00e8 all\u2019insegna dei gelati anni \u201980 - \u00e8campania","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ecampania.it\/magazine\/caserta-alla-gelateria-la-fenice-la-primavera-e-all-insegna-dei-gelati-anni-80\/","og_locale":"it_IT","og_type":"article","og_title":"Caserta, alla gelateria La Fenice la primavera \u00e8 all\u2019insegna dei gelati anni \u201980 - \u00e8campania","og_description":"I gusti rivisitati dalla maestra gelatiera Pina Molitierno Alla gelateria La Fenice di Caserta la primavera \u00e8 all\u2019insegna dei gelati che hanno fatto la storia di questo piacere dalla vita e che nel tempo sono stati un po\u2019 dimenticati. Accanto alla ricca proposta di gusti classici la maestra gelatiera Pina Molitierno ha deciso di dedicare [&hellip;]","og_url":"https:\/\/ecampania.it\/magazine\/caserta-alla-gelateria-la-fenice-la-primavera-e-all-insegna-dei-gelati-anni-80\/","og_site_name":"\u00e8campania","article_publisher":"https:\/\/www.facebook.com\/ecampania.it","article_published_time":"2026-03-26T16:45:27+00:00","article_modified_time":"2026-03-26T17:00:15+00:00","og_image":[{"width":1103,"height":827,"url":"https:\/\/ecampania.it\/magazine\/wp-content\/uploads\/2026\/03\/la-fenice-caserta.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"5 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ecampania.it\/magazine\/caserta-alla-gelateria-la-fenice-la-primavera-e-all-insegna-dei-gelati-anni-80\/#article","isPartOf":{"@id":"https:\/\/ecampania.it\/magazine\/caserta-alla-gelateria-la-fenice-la-primavera-e-all-insegna-dei-gelati-anni-80\/"},"author":{"name":"Redazione","@id":"https:\/\/ecampania.it\/magazine\/#\/schema\/person\/f259cd7c01428ef3ac5db31dcac5ab70"},"headline":"Caserta, alla gelateria La Fenice la primavera \u00e8 all\u2019insegna dei gelati anni \u201980","datePublished":"2026-03-26T16:45:27+00:00","dateModified":"2026-03-26T17:00:15+00:00","mainEntityOfPage":{"@id":"https:\/\/ecampania.it\/magazine\/caserta-alla-gelateria-la-fenice-la-primavera-e-all-insegna-dei-gelati-anni-80\/"},"wordCount":608,"commentCount":0,"publisher":{"@id":"https:\/\/ecampania.it\/magazine\/#organization"},"image":{"@id":"https:\/\/ecampania.it\/magazine\/caserta-alla-gelateria-la-fenice-la-primavera-e-all-insegna-dei-gelati-anni-80\/#primaryimage"},"thumbnailUrl":"https:\/\/ecampania.it\/magazine\/wp-content\/uploads\/2026\/03\/la-fenice-caserta.jpg","keywords":["prima"],"articleSection":["Food"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/ecampania.it\/magazine\/caserta-alla-gelateria-la-fenice-la-primavera-e-all-insegna-dei-gelati-anni-80\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/ecampania.it\/magazine\/caserta-alla-gelateria-la-fenice-la-primavera-e-all-insegna-dei-gelati-anni-80\/","url":"https:\/\/ecampania.it\/magazine\/caserta-alla-gelateria-la-fenice-la-primavera-e-all-insegna-dei-gelati-anni-80\/","name":"Caserta, alla gelateria La Fenice la primavera \u00e8 all\u2019insegna dei gelati anni \u201980 - \u00e8campania","isPartOf":{"@id":"https:\/\/ecampania.it\/magazine\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ecampania.it\/magazine\/caserta-alla-gelateria-la-fenice-la-primavera-e-all-insegna-dei-gelati-anni-80\/#primaryimage"},"image":{"@id":"https:\/\/ecampania.it\/magazine\/caserta-alla-gelateria-la-fenice-la-primavera-e-all-insegna-dei-gelati-anni-80\/#primaryimage"},"thumbnailUrl":"https:\/\/ecampania.it\/magazine\/wp-content\/uploads\/2026\/03\/la-fenice-caserta.jpg","datePublished":"2026-03-26T16:45:27+00:00","dateModified":"2026-03-26T17:00:15+00:00","breadcrumb":{"@id":"https:\/\/ecampania.it\/magazine\/caserta-alla-gelateria-la-fenice-la-primavera-e-all-insegna-dei-gelati-anni-80\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ecampania.it\/magazine\/caserta-alla-gelateria-la-fenice-la-primavera-e-all-insegna-dei-gelati-anni-80\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/ecampania.it\/magazine\/caserta-alla-gelateria-la-fenice-la-primavera-e-all-insegna-dei-gelati-anni-80\/#primaryimage","url":"https:\/\/ecampania.it\/magazine\/wp-content\/uploads\/2026\/03\/la-fenice-caserta.jpg","contentUrl":"https:\/\/ecampania.it\/magazine\/wp-content\/uploads\/2026\/03\/la-fenice-caserta.jpg","width":1103,"height":827},{"@type":"BreadcrumbList","@id":"https:\/\/ecampania.it\/magazine\/caserta-alla-gelateria-la-fenice-la-primavera-e-all-insegna-dei-gelati-anni-80\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/ecampania.it\/magazine\/"},{"@type":"ListItem","position":2,"name":"Caserta, alla gelateria La Fenice la primavera \u00e8 all\u2019insegna dei gelati anni \u201980"}]},{"@type":"WebSite","@id":"https:\/\/ecampania.it\/magazine\/#website","url":"https:\/\/ecampania.it\/magazine\/","name":"Ecampania","description":"Il primo portale dedicato al turismo ed alla cultura in Campania","publisher":{"@id":"https:\/\/ecampania.it\/magazine\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ecampania.it\/magazine\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/ecampania.it\/magazine\/#organization","name":"Ecampania","url":"https:\/\/ecampania.it\/magazine\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/ecampania.it\/magazine\/#\/schema\/logo\/image\/","url":"https:\/\/ecampania.it\/magazine\/wp-content\/uploads\/2025\/01\/fb.png","contentUrl":"https:\/\/ecampania.it\/magazine\/wp-content\/uploads\/2025\/01\/fb.png","width":500,"height":500,"caption":"Ecampania"},"image":{"@id":"https:\/\/ecampania.it\/magazine\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ecampania.it","https:\/\/www.instagram.com\/ecampania.it\/"]},{"@type":"Person","@id":"https:\/\/ecampania.it\/magazine\/#\/schema\/person\/f259cd7c01428ef3ac5db31dcac5ab70","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/ecampania.it\/magazine\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/95816d083b7410def6d31c027c3ddb4f82515f84e68ea358ea75203bfac610a7?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/95816d083b7410def6d31c027c3ddb4f82515f84e68ea358ea75203bfac610a7?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/ecampania.it\/magazine\/author\/ecampania\/"}]}},"_links":{"self":[{"href":"https:\/\/ecampania.it\/magazine\/wp-json\/wp\/v2\/posts\/8788","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ecampania.it\/magazine\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ecampania.it\/magazine\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ecampania.it\/magazine\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/ecampania.it\/magazine\/wp-json\/wp\/v2\/comments?post=8788"}],"version-history":[{"count":1,"href":"https:\/\/ecampania.it\/magazine\/wp-json\/wp\/v2\/posts\/8788\/revisions"}],"predecessor-version":[{"id":8794,"href":"https:\/\/ecampania.it\/magazine\/wp-json\/wp\/v2\/posts\/8788\/revisions\/8794"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ecampania.it\/magazine\/wp-json\/wp\/v2\/media\/8795"}],"wp:attachment":[{"href":"https:\/\/ecampania.it\/magazine\/wp-json\/wp\/v2\/media?parent=8788"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ecampania.it\/magazine\/wp-json\/wp\/v2\/categories?post=8788"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ecampania.it\/magazine\/wp-json\/wp\/v2\/tags?post=8788"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}