{"id":9362,"date":"2026-05-08T16:09:26","date_gmt":"2026-05-08T14:09:26","guid":{"rendered":"https:\/\/ecampania.it\/magazine\/?p=9362"},"modified":"2026-05-11T10:14:15","modified_gmt":"2026-05-11T08:14:15","slug":"dalla-polonia-fino-a-pompei-in-20mila-in-piazza-per-pregare-col-papa","status":"publish","type":"post","link":"https:\/\/ecampania.it\/magazine\/dalla-polonia-fino-a-pompei-in-20mila-in-piazza-per-pregare-col-papa\/","title":{"rendered":"Dalla Polonia fino a Pompei, in 20mila in piazza per pregare col Papa"},"content":{"rendered":"\n<p>Sono arrivati in 20mila, molti anche da Napoli, valutando che a Pompei avrebbero potuto approfittare di strade pi\u00f9 tranquille, meno caotiche, per pregare davvero e non solo sventolare fazzoletti o bandierine per salutare il Papa. Ma tutti hanno espresso il desiderio di implorare la Madonna, recitando la supplica composta da San Bartolo Longo per la Regina del santo Rosario. E per questo hanno tributato un grande applauso a Papa Leone XIV quando ha detto &#8220;Nessuna potenza terrena salver\u00e0 il mondo, ma solo la potenza divina dell&#8217;Amore&#8221;.<\/p>\n\n\n\n<p>&#8220;Questi tempi sono difficili &#8211; ha spiegato Tommaso, settantenne di Cava dei Tirreni -. Servirebbe un Papa forte e sto ancora aspettando di capire se il nostro lo sia davvero. Comunque, oggi sarei venuto lo stesso al Santuario, per recitare la Supplica. Anche senza il Pontefice&#8221;.<\/p>\n\n\n\n<p>Sorridenti si sono strette tra loro le donne di un gruppo proveniente dalla Polonia. Non erano le sole a venire da diversi paesi d&#8217;Europa. Non parlavano una parola in italiano ma hanno pregato con fervore, con Suor Maddalena, religiosa connazionale che ora si trova a Roma.<\/p>\n\n\n\n<p>Felici di trovarsi sul corridoio che ha percorso il Papa, due giovanissime famiglie di immigrati, una indiana con bambini di 6 e 1 anno, e l&#8217;altra dello Sri Lanka con il piccolo Nethan di 3 anni e Liam di soli 2 mesi, che fanno base a Nocera Inferiore e a Napoli. Da Boscoreale una decina di ragazzi entusiasti di Papa Leone: &#8220;Portiamo con noi l&#8217;immagine di Maria SS. Liberatrice, che fu rinvenuta al tempo di Bartolo Longo, quando stava decidendo dove edificare il Santuario per la Madonna del Rosario. Era il 27 marzo 1899. Scelse Pompei, ma avrebbe dovuto sorgere nel nostro Paese e anche da noi si recita una bellissima supplica, come oggi qui&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sono arrivati in 20mila, molti anche da Napoli, valutando che a Pompei avrebbero potuto approfittare di strade pi\u00f9 tranquille, meno caotiche, per pregare davvero e non solo sventolare fazzoletti o bandierine per salutare il Papa. Ma tutti hanno espresso il desiderio di implorare la Madonna, recitando la supplica composta da San Bartolo Longo per la [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":9363,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jnews-multi-image_gallery":[],"jnews_single_post":{"format":"standard"},"jnews_primary_category":[],"jnews_override_counter":[],"footnotes":""},"categories":[7],"tags":[393,93],"class_list":["post-9362","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eventi","tag-papa","tag-pompei"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Dalla Polonia fino a Pompei, in 20mila in piazza per pregare col Papa - \u00e8campania<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ecampania.it\/magazine\/dalla-polonia-fino-a-pompei-in-20mila-in-piazza-per-pregare-col-papa\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dalla Polonia fino a Pompei, in 20mila in piazza per pregare col Papa - \u00e8campania\" \/>\n<meta property=\"og:description\" content=\"Sono arrivati in 20mila, molti anche da Napoli, valutando che a Pompei avrebbero potuto approfittare di strade pi\u00f9 tranquille, meno caotiche, per pregare davvero e non solo sventolare fazzoletti o bandierine per salutare il Papa. Ma tutti hanno espresso il desiderio di implorare la Madonna, recitando la supplica composta da San Bartolo Longo per la [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ecampania.it\/magazine\/dalla-polonia-fino-a-pompei-in-20mila-in-piazza-per-pregare-col-papa\/\" \/>\n<meta property=\"og:site_name\" content=\"\u00e8campania\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ecampania.it\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-08T14:09:26+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-11T08:14:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ecampania.it\/magazine\/wp-content\/uploads\/2026\/05\/Screenshot_20260508_160555_Facebook.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"896\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/ecampania.it\/magazine\/dalla-polonia-fino-a-pompei-in-20mila-in-piazza-per-pregare-col-papa\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/ecampania.it\/magazine\/dalla-polonia-fino-a-pompei-in-20mila-in-piazza-per-pregare-col-papa\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\/\/ecampania.it\/magazine\/#\/schema\/person\/f259cd7c01428ef3ac5db31dcac5ab70\"},\"headline\":\"Dalla Polonia fino a Pompei, in 20mila in piazza per pregare col Papa\",\"datePublished\":\"2026-05-08T14:09:26+00:00\",\"dateModified\":\"2026-05-11T08:14:15+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/ecampania.it\/magazine\/dalla-polonia-fino-a-pompei-in-20mila-in-piazza-per-pregare-col-papa\/\"},\"wordCount\":300,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/ecampania.it\/magazine\/#organization\"},\"image\":{\"@id\":\"https:\/\/ecampania.it\/magazine\/dalla-polonia-fino-a-pompei-in-20mila-in-piazza-per-pregare-col-papa\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/ecampania.it\/magazine\/wp-content\/uploads\/2026\/05\/Screenshot_20260508_160555_Facebook.jpg\",\"keywords\":[\"papa\",\"POMPEI\"],\"articleSection\":[\"Eventi\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/ecampania.it\/magazine\/dalla-polonia-fino-a-pompei-in-20mila-in-piazza-per-pregare-col-papa\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ecampania.it\/magazine\/dalla-polonia-fino-a-pompei-in-20mila-in-piazza-per-pregare-col-papa\/\",\"url\":\"https:\/\/ecampania.it\/magazine\/dalla-polonia-fino-a-pompei-in-20mila-in-piazza-per-pregare-col-papa\/\",\"name\":\"Dalla Polonia fino a Pompei, in 20mila in piazza per pregare col Papa - \u00e8campania\",\"isPartOf\":{\"@id\":\"https:\/\/ecampania.it\/magazine\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/ecampania.it\/magazine\/dalla-polonia-fino-a-pompei-in-20mila-in-piazza-per-pregare-col-papa\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/ecampania.it\/magazine\/dalla-polonia-fino-a-pompei-in-20mila-in-piazza-per-pregare-col-papa\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/ecampania.it\/magazine\/wp-content\/uploads\/2026\/05\/Screenshot_20260508_160555_Facebook.jpg\",\"datePublished\":\"2026-05-08T14:09:26+00:00\",\"dateModified\":\"2026-05-11T08:14:15+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/ecampania.it\/magazine\/dalla-polonia-fino-a-pompei-in-20mila-in-piazza-per-pregare-col-papa\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ecampania.it\/magazine\/dalla-polonia-fino-a-pompei-in-20mila-in-piazza-per-pregare-col-papa\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/ecampania.it\/magazine\/dalla-polonia-fino-a-pompei-in-20mila-in-piazza-per-pregare-col-papa\/#primaryimage\",\"url\":\"https:\/\/ecampania.it\/magazine\/wp-content\/uploads\/2026\/05\/Screenshot_20260508_160555_Facebook.jpg\",\"contentUrl\":\"https:\/\/ecampania.it\/magazine\/wp-content\/uploads\/2026\/05\/Screenshot_20260508_160555_Facebook.jpg\",\"width\":1080,\"height\":896},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ecampania.it\/magazine\/dalla-polonia-fino-a-pompei-in-20mila-in-piazza-per-pregare-col-papa\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/ecampania.it\/magazine\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Dalla Polonia fino a Pompei, in 20mila in piazza per pregare col Papa\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ecampania.it\/magazine\/#website\",\"url\":\"https:\/\/ecampania.it\/magazine\/\",\"name\":\"Ecampania\",\"description\":\"Il primo portale dedicato al turismo ed alla cultura in Campania\",\"publisher\":{\"@id\":\"https:\/\/ecampania.it\/magazine\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ecampania.it\/magazine\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/ecampania.it\/magazine\/#organization\",\"name\":\"Ecampania\",\"url\":\"https:\/\/ecampania.it\/magazine\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/ecampania.it\/magazine\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/ecampania.it\/magazine\/wp-content\/uploads\/2025\/01\/fb.png\",\"contentUrl\":\"https:\/\/ecampania.it\/magazine\/wp-content\/uploads\/2025\/01\/fb.png\",\"width\":500,\"height\":500,\"caption\":\"Ecampania\"},\"image\":{\"@id\":\"https:\/\/ecampania.it\/magazine\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/ecampania.it\",\"https:\/\/www.instagram.com\/ecampania.it\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/ecampania.it\/magazine\/#\/schema\/person\/f259cd7c01428ef3ac5db31dcac5ab70\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/ecampania.it\/magazine\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/95816d083b7410def6d31c027c3ddb4f82515f84e68ea358ea75203bfac610a7?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/95816d083b7410def6d31c027c3ddb4f82515f84e68ea358ea75203bfac610a7?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\/\/ecampania.it\/magazine\/author\/ecampania\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Dalla Polonia fino a Pompei, in 20mila in piazza per pregare col Papa - \u00e8campania","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ecampania.it\/magazine\/dalla-polonia-fino-a-pompei-in-20mila-in-piazza-per-pregare-col-papa\/","og_locale":"it_IT","og_type":"article","og_title":"Dalla Polonia fino a Pompei, in 20mila in piazza per pregare col Papa - \u00e8campania","og_description":"Sono arrivati in 20mila, molti anche da Napoli, valutando che a Pompei avrebbero potuto approfittare di strade pi\u00f9 tranquille, meno caotiche, per pregare davvero e non solo sventolare fazzoletti o bandierine per salutare il Papa. Ma tutti hanno espresso il desiderio di implorare la Madonna, recitando la supplica composta da San Bartolo Longo per la [&hellip;]","og_url":"https:\/\/ecampania.it\/magazine\/dalla-polonia-fino-a-pompei-in-20mila-in-piazza-per-pregare-col-papa\/","og_site_name":"\u00e8campania","article_publisher":"https:\/\/www.facebook.com\/ecampania.it","article_published_time":"2026-05-08T14:09:26+00:00","article_modified_time":"2026-05-11T08:14:15+00:00","og_image":[{"width":1080,"height":896,"url":"https:\/\/ecampania.it\/magazine\/wp-content\/uploads\/2026\/05\/Screenshot_20260508_160555_Facebook.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ecampania.it\/magazine\/dalla-polonia-fino-a-pompei-in-20mila-in-piazza-per-pregare-col-papa\/#article","isPartOf":{"@id":"https:\/\/ecampania.it\/magazine\/dalla-polonia-fino-a-pompei-in-20mila-in-piazza-per-pregare-col-papa\/"},"author":{"name":"Redazione","@id":"https:\/\/ecampania.it\/magazine\/#\/schema\/person\/f259cd7c01428ef3ac5db31dcac5ab70"},"headline":"Dalla Polonia fino a Pompei, in 20mila in piazza per pregare col Papa","datePublished":"2026-05-08T14:09:26+00:00","dateModified":"2026-05-11T08:14:15+00:00","mainEntityOfPage":{"@id":"https:\/\/ecampania.it\/magazine\/dalla-polonia-fino-a-pompei-in-20mila-in-piazza-per-pregare-col-papa\/"},"wordCount":300,"commentCount":0,"publisher":{"@id":"https:\/\/ecampania.it\/magazine\/#organization"},"image":{"@id":"https:\/\/ecampania.it\/magazine\/dalla-polonia-fino-a-pompei-in-20mila-in-piazza-per-pregare-col-papa\/#primaryimage"},"thumbnailUrl":"https:\/\/ecampania.it\/magazine\/wp-content\/uploads\/2026\/05\/Screenshot_20260508_160555_Facebook.jpg","keywords":["papa","POMPEI"],"articleSection":["Eventi"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/ecampania.it\/magazine\/dalla-polonia-fino-a-pompei-in-20mila-in-piazza-per-pregare-col-papa\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/ecampania.it\/magazine\/dalla-polonia-fino-a-pompei-in-20mila-in-piazza-per-pregare-col-papa\/","url":"https:\/\/ecampania.it\/magazine\/dalla-polonia-fino-a-pompei-in-20mila-in-piazza-per-pregare-col-papa\/","name":"Dalla Polonia fino a Pompei, in 20mila in piazza per pregare col Papa - \u00e8campania","isPartOf":{"@id":"https:\/\/ecampania.it\/magazine\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ecampania.it\/magazine\/dalla-polonia-fino-a-pompei-in-20mila-in-piazza-per-pregare-col-papa\/#primaryimage"},"image":{"@id":"https:\/\/ecampania.it\/magazine\/dalla-polonia-fino-a-pompei-in-20mila-in-piazza-per-pregare-col-papa\/#primaryimage"},"thumbnailUrl":"https:\/\/ecampania.it\/magazine\/wp-content\/uploads\/2026\/05\/Screenshot_20260508_160555_Facebook.jpg","datePublished":"2026-05-08T14:09:26+00:00","dateModified":"2026-05-11T08:14:15+00:00","breadcrumb":{"@id":"https:\/\/ecampania.it\/magazine\/dalla-polonia-fino-a-pompei-in-20mila-in-piazza-per-pregare-col-papa\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ecampania.it\/magazine\/dalla-polonia-fino-a-pompei-in-20mila-in-piazza-per-pregare-col-papa\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/ecampania.it\/magazine\/dalla-polonia-fino-a-pompei-in-20mila-in-piazza-per-pregare-col-papa\/#primaryimage","url":"https:\/\/ecampania.it\/magazine\/wp-content\/uploads\/2026\/05\/Screenshot_20260508_160555_Facebook.jpg","contentUrl":"https:\/\/ecampania.it\/magazine\/wp-content\/uploads\/2026\/05\/Screenshot_20260508_160555_Facebook.jpg","width":1080,"height":896},{"@type":"BreadcrumbList","@id":"https:\/\/ecampania.it\/magazine\/dalla-polonia-fino-a-pompei-in-20mila-in-piazza-per-pregare-col-papa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/ecampania.it\/magazine\/"},{"@type":"ListItem","position":2,"name":"Dalla Polonia fino a Pompei, in 20mila in piazza per pregare col Papa"}]},{"@type":"WebSite","@id":"https:\/\/ecampania.it\/magazine\/#website","url":"https:\/\/ecampania.it\/magazine\/","name":"Ecampania","description":"Il primo portale dedicato al turismo ed alla cultura in Campania","publisher":{"@id":"https:\/\/ecampania.it\/magazine\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ecampania.it\/magazine\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/ecampania.it\/magazine\/#organization","name":"Ecampania","url":"https:\/\/ecampania.it\/magazine\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/ecampania.it\/magazine\/#\/schema\/logo\/image\/","url":"https:\/\/ecampania.it\/magazine\/wp-content\/uploads\/2025\/01\/fb.png","contentUrl":"https:\/\/ecampania.it\/magazine\/wp-content\/uploads\/2025\/01\/fb.png","width":500,"height":500,"caption":"Ecampania"},"image":{"@id":"https:\/\/ecampania.it\/magazine\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ecampania.it","https:\/\/www.instagram.com\/ecampania.it\/"]},{"@type":"Person","@id":"https:\/\/ecampania.it\/magazine\/#\/schema\/person\/f259cd7c01428ef3ac5db31dcac5ab70","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/ecampania.it\/magazine\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/95816d083b7410def6d31c027c3ddb4f82515f84e68ea358ea75203bfac610a7?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/95816d083b7410def6d31c027c3ddb4f82515f84e68ea358ea75203bfac610a7?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/ecampania.it\/magazine\/author\/ecampania\/"}]}},"_links":{"self":[{"href":"https:\/\/ecampania.it\/magazine\/wp-json\/wp\/v2\/posts\/9362","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ecampania.it\/magazine\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ecampania.it\/magazine\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ecampania.it\/magazine\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/ecampania.it\/magazine\/wp-json\/wp\/v2\/comments?post=9362"}],"version-history":[{"count":2,"href":"https:\/\/ecampania.it\/magazine\/wp-json\/wp\/v2\/posts\/9362\/revisions"}],"predecessor-version":[{"id":9365,"href":"https:\/\/ecampania.it\/magazine\/wp-json\/wp\/v2\/posts\/9362\/revisions\/9365"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ecampania.it\/magazine\/wp-json\/wp\/v2\/media\/9363"}],"wp:attachment":[{"href":"https:\/\/ecampania.it\/magazine\/wp-json\/wp\/v2\/media?parent=9362"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ecampania.it\/magazine\/wp-json\/wp\/v2\/categories?post=9362"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ecampania.it\/magazine\/wp-json\/wp\/v2\/tags?post=9362"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}